{"id":6165,"date":"2018-05-21T18:21:07","date_gmt":"2018-05-21T22:21:07","guid":{"rendered":"https:\/\/printcenter.org\/100\/?page_id=6165"},"modified":"2018-06-15T13:41:55","modified_gmt":"2018-06-15T17:41:55","slug":"press-images-92","status":"publish","type":"page","link":"https:\/\/printcenter.org\/100\/press-images-92\/","title":{"rendered":"Press Images: <i>92nd ANNUAL<\/i>"},"content":{"rendered":"","protected":true},"excerpt":{"rendered":"","protected":true},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-fullwidth.php","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"class_list":["post-6165","page","type-page","status-publish","post-password-required","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/printcenter.org\/100\/wp-json\/wp\/v2\/pages\/6165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/printcenter.org\/100\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/printcenter.org\/100\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/printcenter.org\/100\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/printcenter.org\/100\/wp-json\/wp\/v2\/comments?post=6165"}],"version-history":[{"count":11,"href":"https:\/\/printcenter.org\/100\/wp-json\/wp\/v2\/pages\/6165\/revisions"}],"predecessor-version":[{"id":6167,"href":"https:\/\/printcenter.org\/100\/wp-json\/wp\/v2\/pages\/6165\/revisions\/6167"}],"wp:attachment":[{"href":"https:\/\/printcenter.org\/100\/wp-json\/wp\/v2\/media?parent=6165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}